{"id":14446,"date":"2013-09-12T14:18:31","date_gmt":"2013-09-12T14:18:31","guid":{"rendered":"https:\/\/www.bhadas4media.com\/old1\/2013\/09\/12\/%e0%a4%ad%e0%a4%be%e0%a4%9c%e0%a4%aa%e0%a4%be-%e0%a4%95%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%b7%e0%a5%8d%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%af-%e0%a4%87%e0%a4%82%e0%a4%a4%e0%a4%95%e0%a4%be\/"},"modified":"2013-09-12T14:18:31","modified_gmt":"2013-09-12T14:18:31","slug":"%e0%a4%ad%e0%a4%be%e0%a4%9c%e0%a4%aa%e0%a4%be-%e0%a4%95%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%b7%e0%a5%8d%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%af-%e0%a4%87%e0%a4%82%e0%a4%a4%e0%a4%95%e0%a4%be","status":"publish","type":"post","link":"https:\/\/www.bhadas4media.com\/old1\/%e0%a4%ad%e0%a4%be%e0%a4%9c%e0%a4%aa%e0%a4%be-%e0%a4%95%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%b7%e0%a5%8d%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%af-%e0%a4%87%e0%a4%82%e0%a4%a4%e0%a4%95%e0%a4%be\/","title":{"rendered":"\u092d\u093e\u091c\u092a\u093e \u0915\u093e &#8221;\u0930\u093e\u0937\u094d\u091f\u094d\u0930\u0940\u092f \u0907\u0902\u0924\u0915\u093e\u0932&#8221;&#8230;. \u0925\u094b\u095c\u093e \u0935\u0958\u094d\u0924 \u0939\u0948"},"content":{"rendered":"<p> \t1984 \u092e\u0947\u0902, \u0906\u091c \u0915\u0940 \u0924\u093e\u0930\u0940\u0916 \u092e\u0947\u0902 \u0926\u094b \u0930\u093e\u0937\u094d\u091f\u094d\u0930\u0940\u092f \u092a\u093e\u0930\u094d\u091f\u0940 \u092e\u0947\u0902 \u0938\u0947 \u090f\u0915 \u0915\u093e \u0924\u092e\u0917\u093e \u0939\u093e\u0938\u093f\u0932, \u092d\u093e\u091c\u092a\u093e \u0915\u0947 \u092a\u093e\u0938 \u0938\u093f\u0930\u094d\u092b 2 \u0938\u0940\u091f \u0925\u0940 ! \u0907\u092e\u0930\u091c\u0947\u0902\u0938\u0940 \u0915\u0947 \u092c\u093e\u0926 \u0915\u093e\u0902\u0917\u094d\u0930\u0947\u0938 \u0935\u093e\u092a\u093f\u0938 \u0938\u0924\u094d\u0924\u093e \u092e\u0947\u0902 \u0932\u094c\u091f\u0940 \u0925\u0940 \u0914\u0930 \u091c\u0928\u0924\u093e \u092a\u093e\u0930\u094d\u091f\u0940 \u0915\u093e \u0935\u095b\u0928 \u0924\u0947\u095b\u0940 \u0938\u0947 \u0918\u091f \u0930\u0939\u093e \u0925\u093e ! \u091c\u0928\u0924\u093e \u092a\u093e\u0930\u094d\u091f\u0940 \u0915\u0947 \u0926\u094b \u0915\u0926\u094d\u0926\u093e\u0935\u0930 , \u0924\u0924\u094d\u0915\u093e\u0932\u0940\u0928, \u092e\u0902\u0924\u094d\u0930\u0940 (\u0935\u093f\u0926\u0947\u0936 \u092e\u0902\u0924\u094d\u0930\u0940 \u0905\u091f\u0932 \u092c\u093f\u0939\u093e\u0930\u0940 \u0935\u093e\u091c\u092a\u0947\u092f\u0940 \u0914\u0930 \u0938\u0942\u091a\u0928\u093e \u092a\u094d\u0930\u0938\u093e\u0930\u0923 \u092e\u0902\u0924\u094d\u0930\u0940 \u0932\u093e\u0932\u0915\u0943\u0937\u094d\u0923 \u0906\u0921\u0935\u093e\u0928\u0940) \u0905\u0932\u0917 \u0939\u094b\u0915\u0930 \u091c\u0928\u0938\u0902\u0918 \u0915\u094b \u092d\u093e\u091c\u092a\u093e \u0915\u093e \u092e\u0941\u0916\u094c\u091f\u093e \u092a\u0939\u0928\u093e \u091a\u0941\u0915\u0947 \u0925\u0947 ! \u092f\u093e\u0928\u093f 1980 \u092e\u0947\u0902 \u092d\u093e\u091c\u092a\u093e \u0905\u0938\u094d\u0924\u093f\u0924\u094d\u0935 \u092e\u0947\u0902 \u0906\u092f\u0940 !<\/p>\n<p> \t\u0924\u092c \u0938\u0947 \u0932\u0947\u0915\u0930 \u0905\u092c \u0924\u0915 \u0907\u0938\u0947 (\u092d\u093e\u091c\u092a\u093e \u0915\u094b) \u0938\u093f\u0930\u094d\u092b 2 \u0928\u093e\u092e\u094b\u0902 \u0938\u0947 \u0939\u0940 \u092a\u0939\u091a\u093e\u0928\u093e \u0917\u092f\u093e- \u0905\u091f\u0932 \u092c\u093f\u0939\u093e\u0930\u0940 \u0935\u093e\u091c\u092a\u0947\u092f\u0940 \u0914\u0930 \u0932\u093e\u0932\u0915\u0943\u0937\u094d\u0923 \u0906\u0921\u0935\u093e\u0928\u0940 ! \u091c\u0928\u0938\u0902\u0918&nbsp; \u0915\u0940 \u091c\u0917\u0939 \u0938\u0902\u0918 \u0915\u093e \u092c\u093e\u0939\u0941\u092c\u0932 \u091a\u0932\u0928\u0947 \u0932\u0917\u093e ! \u092e\u0917\u0930 \u0938\u0902\u0918 \u0915\u0940 \u0907\u0938 \u0930\u093e\u091c\u0928\u0940\u0924\u093f\u0915 \u0936\u093e\u0916\u093e (\u092d\u093e\u091c\u092a\u093e) \u0915\u094b \u0938\u0902\u0938\u0926 \u092e\u0947\u0902 \u0938\u0940\u091f\u094b\u0902 \u0915\u0940 \u095b\u0930\u0941\u0930\u0924 \u0925\u0940 \u0914\u0930 \u0907\u0938\u0915\u0947 \u0932\u093f\u090f \u0916\u0941\u0932\u0915\u0930 \u0930\u093e\u091c\u0928\u0940\u0924\u093f \u0915\u0930\u0928\u0947 \u0935\u093e\u0932\u0947 \u092c\u095c\u0947 \u0928\u093e\u092e\u094b\u0902 \u0915\u0940 \u092d\u0940 ! \u095b\u093e\u0939\u093f\u0930 \u0939\u0948, \u0905\u091f\u0932 \u0914\u0930 \u0906\u0921\u0935\u093e\u0928\u0940 \u0915\u0947 \u0905\u0932\u093e\u0935\u093e \u0938\u0902\u0918 \u0915\u0940 \u0938\u0902\u091c\u0940\u0935\u0928\u0940 \u092c\u0942\u091f\u0940 \u0915\u094b\u0908 \u0928\u0939\u0940\u0902 \u0925\u093e ! \u0915\u093e\u0930\u0935\u093e\u0902 \u092c\u095d\u093e ! \u092d\u093e\u091c\u092a\u093e \u0928\u0947 2 \u092c\u093e\u0930 \u0938\u0924\u094d\u0924\u093e \u0915\u093e \u0938\u094d\u0935\u093e\u0926 \u091a\u0916\u093e ! \u0938\u0902\u0918 \u0915\u0947 \u092a\u093e\u0938 \u0905\u092c, \u092d\u093e\u091c\u092a\u093e \u0915\u0947 \u0930\u0942\u092a \u092e\u0947\u0902, \u090f\u0915 \u0924\u093e\u0958\u0924\u0935\u0930 \u0930\u093e\u091c\u0928\u0940\u0924\u093f\u0915 \u0939\u0925\u093f\u092f\u093e\u0930 \u0925\u093e !<\/p>\n<p> \t\u0932\u0947\u0915\u093f\u0928 \u092f\u0939\u093e\u0901 \u090f\u0915 \u092c\u093e\u0924 \u0917\u094c\u0930 \u0915\u0930\u0928\u0947 \u0935\u093e\u0932\u0940 \u0939\u0948 \u0915\u093f&#8230;\u092a\u093e\u0930\u094d\u091f\u0940 \u0935\u093f\u0925 \u0921\u093f\u095e\u0930\u0947\u0902\u0938 \u0928\u0947, \u092a\u0930\u093f\u0935\u093e\u0930 \u0914\u0930 \u0905\u0928\u0941\u0936\u093e\u0938\u0928 \u0915\u094b \u0915\u0930\u0940\u092c-\u0915\u0930\u0940\u092c 2010 \u0924\u0915 \u0938\u0902\u091c\u094b\u092f\u0947 \u0930\u0916\u093e ! \u092e\u0939\u0924\u094d\u0924\u094d\u0935\u093e\u0915\u093e\u0902\u0915\u094d\u0937\u093e \u0914\u0930 \u092a\u0930\u093f\u0935\u093e\u0930-\u0935\u093e\u0926 \u0915\u094b \u092a\u0928\u092a\u0928\u0947 \u0915\u0940 \u092c\u091c\u093e\u092f, \u0924\u095b\u0941\u0930\u094d\u092c\u0947 \u0914\u0930 \u0958\u093e\u092c\u093f\u0932\u093f\u092f\u0924 \u0915\u094b \u0924\u0930\u093e\u0936\u093e&#8230;\u092a\u094d\u0930\u094b\u0924\u094d\u0938\u093e\u0939\u093f\u0924 \u0915\u093f\u092f\u093e ! \u092e\u0917\u0930 2010 \u0915\u0947 \u092c\u093e\u0926&nbsp; \u092d\u093e\u091c\u092a\u093e \u092c\u0926\u0932 \u0938\u0940 \u0917\u092f\u0940 \u0914\u0930 \u091a\u0932 \u092a\u0921\u0940 \u091c\u0928\u0924\u093e \u092a\u093e\u0930\u094d\u091f\u0940 \u0915\u0940 \u0930\u093e\u0939 \u092a\u0930 ! \u0935\u094d\u092f\u0915\u094d\u0924\u093f\u0917\u0924 \u092e\u0939\u0924\u094d\u0924\u094d\u0935\u093e\u0915\u093e\u0902\u0915\u094d\u0937\u093e \u092a\u0930\u0935\u093e\u0928 \u091a\u095c\u0928\u0947 \u0932\u0917\u0940 \u0914\u0930 \u092a\u093e\u0930\u094d\u091f\u0940 \u0915\u0940 \u0909\u092a\u0932\u092c\u094d\u0927\u093f\u092f\u094b\u0902 \u092a\u0930 \u0917\u0930\u094d\u0935 \u0915\u0930\u0928\u0947 \u0915\u0940 \u092c\u091c\u093e\u092f \u0935\u094d\u092f\u0915\u094d\u0924\u093f-\u0935\u093f\u0936\u0947\u0937 \u092a\u0930 \u091c\u094b\u0930 \u0926\u093f\u092f\u093e \u091c\u093e\u0928\u0947 \u0932\u0917\u093e&#8230;.\u0915\u092e\u094b\u092c\u0947\u0936 \u0909\u0938\u0940 \u0924\u0930\u094d\u095b \u092a\u0930 , \u091c\u0948\u0938\u0947 \u091c\u0928\u0924\u093e \u092a\u093e\u0930\u094d\u091f\u0940 \u0915\u0947 \u0907\u092e\u0930\u091c\u0947\u0902\u0938\u0940 \u0915\u0947 &quot;\u092f\u0941\u0935\u093e \u0928\u093e\u092f\u0915\u094b\u0902&quot; (\u092e\u0941\u0932\u093e\u092f\u092e, \u0932\u093e\u0932\u0942, \u0928\u0940\u0924\u0940\u0936 \u0935\u0917\u0948\u0930\u0939) \u0914\u0930 &quot;\u0936\u0940\u0930\u094d\u0937 \u0928\u0947\u0924\u0943\u0924\u094d\u0935&quot; (\u091a\u0902\u0926\u094d\u0930\u0936\u0947\u0916\u0930 \u091c\u0948\u0938\u0947 \u0914\u0930 \u0915\u0908&#8230;) \u0928\u0947 \u0916\u0941\u0926 \u0915\u0940 \u092e\u0939\u0924\u094d\u0924\u094d\u0935\u093e\u0915\u093e\u0902\u0915\u094d\u0937\u093e \u0915\u094b \u0907\u0938 \u0915\u0926\u0930 \u092c\u0922\u093e\u092f\u093e \u0915\u093f \u0935\u0958\u094d\u0924 \u0906\u0928\u0947 \u092a\u0930 \u0905\u092a\u0928\u0940 \u0930\u093e\u0939 \u091c\u0941\u0926\u093e \u0915\u0930 \u0932\u093f\u090f ! \u0907\u0928\u092e\u0947\u0902 \u0938\u0947 \u0915\u0908 \u0932\u094b\u0917,&nbsp; \u0915\u0941\u091b \u0930\u093e\u091c\u094d\u092f\u094b\u0902 \u0915\u0947 \u092e\u0941\u0916\u094d\u092f\u092e\u0902\u0924\u094d\u0930\u0940 \u092c\u0928 \u0915\u0930 \u0916\u0941\u0926 \u0915\u094b \u0915\u094d\u0937\u0947\u0924\u094d\u0930\u0940\u092f \u092a\u093e\u0930\u094d\u091f\u093f\u092f\u094b\u0902 \u0915\u093e \u092c\u0949\u0938 \u092e\u093e\u0928 \u0915\u0930 \u0916\u0941\u0936 \u0939\u0948\u0902 \u0914\u0930 \u091a\u0902\u0926\u094d\u0930\u0936\u0947\u0916\u0930 \u091c\u0948\u0938\u0947 \u0932\u094b\u0917 , \u0905\u0932\u094d\u092a\u0915\u093e\u0932 \u0915\u0947 \u0932\u093f\u090f \u0939\u0940 \u0938\u0939\u0940, \u092a\u094d\u0930\u0927\u093e\u0928\u092e\u0902\u0924\u094d\u0930\u0940 \u0915\u0940 \u0915\u0941\u0930\u094d\u0938\u0940 \u0939\u0925\u093f\u092f\u093e\u0928\u0947 \u092e\u0947\u0902 \u0938\u092b\u0932 \u0930\u0939\u0947 ! \u091c\u0928\u0924\u093e \u092a\u093e\u0930\u094d\u091f\u0940 (\u0926\u0932) \u0915\u093e &quot;\u0930\u093e\u0937\u094d\u091f\u094d\u0930\u0940\u092f \u092a\u093e\u0930\u094d\u091f\u0940 &quot; \u0939\u094b\u0928\u0947 \u0915\u093e \u091f\u0948\u0917 \u091b\u0940\u0928 \u0917\u092f\u093e ! \u091f\u0942\u091f\u0924\u0947-\u091f\u0942\u091f\u0924\u0947, \u091c\u0928\u0924\u093e \u092a\u093e\u0930\u094d\u091f\u0940 \u0907\u0924\u0928\u093e \u091f\u0942\u091f\u0940 \u0915\u093f \u0906\u091c \u091c\u0928\u0924\u093e \u092a\u093e\u0930\u094d\u091f\u0940 \u0915\u093e \u0928\u093e\u092e\u0932\u0947\u0935\u093e \u092d\u0940 \u0915\u094b\u0908 \u0928\u0939\u0940\u0902 \u092c\u091a\u093e ! \u0906\u091c \u0909\u0938\u0940 \u0930\u093e\u0939 \u092a\u0930 \u092c\u0940.\u091c\u0947.\u092a\u0940. \u0939\u0948 ! \u092d\u093e\u091c\u092a\u093e \u0936\u093e\u0938\u093f\u0924 \u0915\u0908 \u0917\u0930\u0940\u092c \u0930\u093e\u091c\u094d\u092f\u094b\u0902 \u0915\u0947 \u092e\u0941\u0916\u094d\u092f\u092e\u0902\u0924\u094d\u0930\u093f\u092f\u094b\u0902 \u0928\u0947 \u0936\u093e\u0928\u0926\u093e\u0930 \u0915\u093e\u092e \u0915\u093f\u092f\u093e ! \u0914\u0930 \u0905\u092a\u0928\u0947 \u0917\u0930\u0940\u092c \u0930\u093e\u091c\u094d\u092f \u0915\u094b \u092e\u0927\u094d\u092f\u092e \u0936\u094d\u0930\u0947\u0923\u0940 \u0915\u0940 \u0938\u0940\u095d\u0940 \u092a\u0930 \u0932\u093e\u0928\u0947 \u092e\u0947\u0902 \u0938\u092b\u0932 \u0930\u0939\u0947 ! \u092a\u0930 \u0930\u093e\u0937\u094d\u091f\u094d\u0930\u0940\u092f \u0938\u094d\u0924\u0930 \u092a\u0930 \u091a\u0930\u094d\u091a\u093e \u092e\u0947\u0902&#8230;.\u0939\u092e\u0947\u0936\u093e \u0905\u092e\u0940\u0930 \u0930\u093e\u091c\u094d\u092f \u0915\u0940 \u0936\u094d\u0930\u0947\u0923\u0940 \u092e\u0947\u0902 \u0936\u0941\u092e\u093e\u0930 , \u0917\u0941\u091c\u0930\u093e\u0924, \u0915\u0947 \u092e\u0941\u0916\u094d\u092f\u092e\u0902\u0924\u094d\u0930\u0940 \u0928\u0930\u0947\u0902\u0926\u094d\u0930 \u092e\u094b\u0926\u0940 \u0939\u0940 \u0930\u0939\u0947 !<\/p>\n<p> \t\u0930\u093e\u0937\u094d\u091f\u094d\u0930\u0940\u092f \u0938\u094d\u0924\u0930 \u092a\u0930 \u0928\u0930\u0947\u0902\u0926\u094d\u0930 \u092e\u094b\u0926\u0940 \u0915\u092c \u0938\u0947 \u0938\u0915\u094d\u0930\u093f\u092f \u0939\u0948\u0902 \u0914\u0930 \u0930\u093e\u0937\u094d\u091f\u094d\u0930\u0940\u092f \u0938\u094d\u0924\u0930 \u092a\u0930 \u0909\u0928\u0915\u093e \u092f\u094b\u0917\u0926\u093e\u0928 \u092a\u0942\u0930\u0947 \u0926\u0947\u0936 \u0915\u0947 \u0932\u093f\u090f \u0915\u094d\u092f\u093e \u0930\u0939\u093e , \u0907\u0938 \u092c\u093e\u0924 \u0915\u093e \u0909\u0924\u094d\u0924\u0930 \u0924\u094b \u0928\u0930\u0947\u0902\u0926\u094d\u0930 \u092e\u094b\u0926\u0940 \u0915\u0947 \u0915\u091f\u094d\u091f\u0930 \u0938\u092e\u0930\u094d\u0925\u0915 \u0938\u0902\u0918 \u092a\u0930\u093f\u0935\u093e\u0930 \u0914\u0930 \u092d\u093e\u091c\u092a\u093e \u0915\u0947 \u0935\u0930\u094d\u0924\u092e\u093e\u0928 \u0905\u0927\u094d\u092f\u0915\u094d\u0937 \u0930\u093e\u091c\u0928\u093e\u0925 \u0938\u093f\u0902\u0939 \u0915\u094b \u092d\u0940 \u0928\u0939\u0940\u0902 \u092a\u0924\u093e ! \u092a\u0930 \u092e\u0940\u0921\u093f\u092f\u093e \u0915\u0940 \u0906\u0902\u0927\u0940 \u0928\u0947 \u092e\u094b\u0926\u0940 \u0915\u094b &quot;\u0906\u092e \u0906\u0926\u092e\u0940 \u0938\u0947 \u0938\u0930\u094b\u0915\u093e\u0930&quot; \u0930\u0916\u0928\u0947 \u0935\u093e\u0932\u093e \u0918\u094b\u0937\u093f\u0924 \u0915\u0930 \u0921\u093e\u0932\u093e ! \u092e\u0940\u0921\u093f\u092f\u093e \u0915\u0947 \u0907\u0938 &quot;\u091b\u093f\u092a\u0947&quot; \u090f\u091c\u0947\u0902\u0921\u093e \u0915\u0947 \u092a\u0940\u091b\u0947 \u0930\u093e\u091c \u0915\u094d\u092f\u093e \u0939\u0948 , \u0907\u0938\u0915\u093e \u0924\u094b \u092a\u0924\u093e \u0928\u0939\u0940\u0902 ,,,\u0932\u0947\u0915\u093f\u0928 \u092e\u0940\u0921\u093f\u092f\u093e \u0915\u0940 \u0907\u0938 \u090f\u0915\u0924\u0930\u095e\u093e \u091a\u093e\u0932 \u0938\u0947 \u092d\u093e\u091c\u092a\u093e \u0915\u0947 \u0935\u094b \u0928\u0947\u0924\u093e \u0928\u0915\u093e\u0930 \u0926\u093f\u090f \u0917\u090f, \u091c\u094b \u0928\u093e \u0938\u093f\u0930\u094d\u092b \u0905\u092a\u0928\u0947 \u092c\u0940\u092e\u093e\u0930\u0942 \u0930\u093e\u091c\u094d\u092f \u0915\u094b \u0926\u0941\u0930\u0942\u0938\u094d\u0924 \u0915\u093f\u092f\u0947 \u092c\u0932\u094d\u0915\u093f \u0915\u0908 \u092e\u093e\u092e\u0932\u094b\u0902 \u092e\u0947\u0902 \u092e\u094b\u0926\u0940 \u0938\u0947 \u0906\u0917\u0947 \u092d\u0940 \u0916\u095c\u0947 \u0926\u093f\u0916\u093e\u0908 \u0926\u093f\u090f ! \u0915\u0947\u0902\u0926\u094d\u0930 \u092e\u0947\u0902 \u0938\u0915\u094d\u0930\u093f\u092f \u092d\u093e\u091c\u092a\u093e \u0915\u0947 \u0915\u0908 \u0928\u0947\u0924\u093e\u0913\u0902 \u0915\u094b \u0938\u0902\u0918 \u0926\u0942\u0927 \u092e\u0947\u0902 \u092a\u095c\u0940 \u092e\u0915\u094d\u0916\u0940 \u0915\u0940 \u0924\u0930\u0939 \u0938\u092e\u091d\u0928\u0947 \u0932\u0917\u093e ! \u0926\u0947\u0936 \u092e\u0947\u0902 \u0915\u093e\u0902\u0917\u094d\u0930\u0947\u0938 \u0915\u0947 \u0916\u093f\u0932\u093e\u092b \u090f\u0915 \u092a\u093e\u0930\u094d\u091f\u0940 \u0915\u094b \u0916\u0921\u093e \u0915\u0930\u0928\u0947 \u0935\u093e\u0932\u0947 \u092d\u093e\u091c\u092a\u093e \u0915\u0947 \u092d\u0940\u0937\u094d\u092e\u092a\u093f\u0924\u093e\u092e\u0939, \u0932\u093e\u0932 \u0915\u0943\u0937\u094d\u0923 \u0906\u0921\u0935\u093e\u0928\u0940 , \u0915\u094b \u0928\u095b\u0930\u0902\u0926\u093e\u095b \u0915\u0930 \u092f\u0947 \u0938\u0928\u094d\u0926\u0947\u0936 \u0926\u0947\u0928\u0947 \u0915\u0940 \u0915\u094b\u0936\u093f\u0936 \u0915\u0940 \u091c\u093e\u0928\u0947 \u0932\u0917\u0940 \u0915\u093f&#8230;&#8230; \u0938\u0924\u094d\u0924\u093e \u0939\u0940 \u0938\u092c \u0915\u0941\u091b \u0939\u0948&#8230;..\u0928\u092e\u0938\u094d\u0924\u0947 \u0938\u0926\u093e \u0935\u0938\u094d\u0924\u094d\u091a\u0932\u0947 \u0938\u0924\u094d\u0924\u093e\u092d\u0941\u092e\u0947 ! \u0938\u0902\u0938\u094d\u0915\u0943\u0924\u093f \u0915\u0940 \u0926\u0941\u0939\u093e\u0908 \u0926\u0947\u0928\u0947 \u0935\u093e\u0932\u0940 \u092d\u093e\u091c\u092a\u093e \u0915\u094b \u092c\u0941\u091c\u0941\u0930\u094d\u0917\u094b\u0902 \u0915\u093e \u0938\u092e\u094d\u092e\u093e\u0928 \u0926\u093f\u0916\u093e\u0908 \u0926\u0947\u0928\u093e \u092c\u0902\u0926 \u0939\u094b \u0917\u092f\u093e ! \u092a\u093e\u0930\u094d\u091f\u0940 \u0915\u094b \u0938\u093f\u0930\u094d\u092b \u0932\u094b\u0915\u0938\u092d\u093e \u0938\u0940\u091f\u094b\u0902 \u0915\u0940 \u091a\u093f\u0902\u0924\u093e \u0939\u0948 , \u0932\u0917\u092d\u0917 \u0909\u0938\u0940 \u0905\u0902\u0926\u093e\u095b \u092e\u0947\u0902 \u091c\u0948\u0938\u0947 1977 \u092e\u0947\u0902 \u091c\u0928\u0924\u093e \u092a\u093e\u0930\u094d\u091f\u0940 \u0915\u094b \u0925\u0940 ! \u0917\u0941\u091c\u0930\u093e\u0924 \u0926\u0902\u0917\u094b\u0902 \u0915\u0947 \u0905\u0932\u093e\u0935\u093e \u0930\u093e\u0937\u094d\u091f\u094d\u0930\u0940\u092f \u0938\u094d\u0924\u0930 \u092a\u0930 \u0928\u0930\u0947\u0902\u0926\u094d\u0930 \u092e\u094b\u0926\u0940 \u0915\u0947 \u092f\u094b\u0917\u0926\u093e\u0928 \u0915\u0940 \u0924\u0932\u093e\u0936 \u091c\u093e\u0930\u0940 \u0939\u0948 ! \u0915\u093e\u0902\u0917\u094d\u0930\u0947\u0938 \u0915\u0940 \u0928\u093e\u0915\u093e\u092e\u0940 \u0915\u094b, \u092e\u094b\u0926\u0940 \u0915\u0940 \u0915\u0942\u092c\u0924 \u092c\u0924\u093e\u0928\u0947 \u0915\u093e \u092a\u094d\u0930\u092f\u093e\u0938 \u095b\u094b\u0930\u094b\u0902 \u092a\u0930 \u0939\u0948 ! \u0905\u092e\u0940\u0930 \u0917\u0941\u091c\u0930\u093e\u0924 \u0915\u094b \u0914\u0930 \u0905\u092e\u0940\u0930 \u092c\u0928\u093e\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u092e\u094b\u0926\u0940 \u0915\u0940 \u092a\u094d\u0930\u0936\u0902\u0938\u093e \u0939\u094b\u0928\u0940 \u091a\u093e\u0939\u093f\u090f \u0914\u0930 \u0939\u094b \u092d\u0940 \u0930\u0939\u0940 \u0939\u0948 ! \u092e\u0917\u0930 \u092f\u0947 \u0909\u092a\u0932\u092c\u094d\u0927\u093f \u0909\u0938\u0940 \u0924\u0930\u0939 \u0915\u0940 \u0939\u0948 , \u091c\u0948\u0938\u0947 \u091f\u093e\u091f\u093e-\u092c\u093f\u0930\u0932\u093e \u0915\u0947 \u0918\u0930 \u0915\u093e \u0938\u092a\u0942\u0924 \u0905\u092a\u0928\u0947 \u0938\u093e\u092e\u094d\u0930\u093e\u091c\u094d\u092f \u0915\u094b \u0906\u0917\u0947 \u092c\u0922\u093e\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0932\u0917\u093e\u0924\u093e\u0930 \u0905\u0917\u094d\u0930\u0938\u0930 \u0939\u094b ! \u092a\u0930 \u090f\u0915 \u0917\u0930\u0940\u092c \u0915\u093e \u092c\u0947\u091f\u093e \u0905\u092a\u0928\u0940 \u092e\u0947\u0939\u0928\u0924 \u0938\u0947 (\u0928\u093e \u0915\u093f \u0935\u093f\u0930\u093e\u0938\u0924 \u092e\u0947\u0902 \u092e\u093f\u0932\u0947) \u0915\u094b\u0908 \u0909\u092a\u0932\u092c\u094d\u0927\u093f \u0939\u093e\u0938\u093f\u0932 \u0915\u0930\u0947 \u0924\u094b \u0935\u093e\u0915\u0908 \u0907\u0938\u0947 \u092f\u094b\u0917\u094d\u092f\u0924\u093e \u0915\u093e \u0938\u0939\u0940 \u092a\u0948\u092e\u093e\u0928\u093e \u092e\u093e\u0928\u093e \u091c\u093e\u0928\u093e \u091a\u093e\u0939\u093f\u090f ! \u0917\u0941\u091c\u0930\u093e\u0924 \u0914\u0930 \u0917\u0930\u0940\u092c \u0930\u093e\u091c\u094d\u092f&nbsp; \u0915\u0947 \u092d\u093e\u091c\u092a\u093e\u0908 \u092e\u0941\u0916\u094d\u092f\u092e\u0902\u0924\u094d\u0930\u093f\u092f\u094b\u0902 \u092e\u0947\u0902 \u0915\u0941\u091b \u0910\u0938\u093e \u0939\u0947 \u0905\u0902\u0924\u0930 \u0939\u0948 !<\/p>\n<p> \t\u092a\u093e\u0930\u094d\u091f\u0940 \u0915\u0940 \u092c\u091c\u093e\u092f \u0935\u094d\u092f\u0915\u094d\u0924\u093f\u0917\u0924 \u0909\u092a\u0932\u092c\u094d\u0927\u093f \u0915\u093e &quot;\u092e\u094b\u0926\u0940 \u091a\u0932\u0928&quot;&#8230;\u0905\u092c \u092d\u093e\u091c\u092a\u093e \u092e\u0947\u0902 \u0906\u092e \u0939\u094b \u091a\u0932\u093e \u0939\u0948 ! \u092a\u093e\u0930\u094d\u091f\u0940 \u0915\u0947 \u0905\u0928\u094d\u0926\u0930, \u0935\u094d\u092f\u0915\u094d\u0924\u093f\u0917\u0924 \u092e\u0939\u0924\u094d\u0924\u094d\u0935\u093e\u0915\u093e\u0902\u0915\u094d\u0937\u093e \u0905\u092c \u0938\u0948\u0926\u094d\u0927\u093e\u0902\u0924\u093f\u0915 \u092c\u093e\u0924 \u0939\u0948 ! \u0938\u0940\u0928\u093f\u092f\u0930-\u091c\u0942\u0928\u093f\u092f\u0930 \u0915\u093e&nbsp; \u0915\u094b\u0908 \u092e\u0924\u0932\u092c \u0928\u0939\u0940\u0902 \u0930\u0939 \u0917\u092f\u093e \u0939\u0948 ! \u092a\u093e\u0930\u094d\u091f\u0940 \u0915\u0940 \u092c\u091c\u093e\u092f \u0935\u094d\u092f\u0915\u094d\u0924\u093f\u0917\u0924 \u091b\u0935\u093f \u0915\u0947 \u092c\u0932 \u092a\u0930 \u092a\u093e\u0930\u094d\u091f\u0940 \u0915\u0947 \u0905\u0928\u094d\u0926\u0930 \u0905\u092a\u0928\u093e \u0915\u0926 \u092c\u0922\u093e\u0928\u0947 \u0915\u0940 \u0907\u0938 \u0915\u0932\u093e \u0915\u094b \u092d\u0932\u0947 \u0939\u0940 \u0932\u094b\u0917 \u0924\u0939\u0947\u0926\u093f\u0932 \u0938\u0947 , \u092b\u093f\u0932\u0939\u093e\u0932, \u092a\u0941\u091a\u0915\u093e\u0930&nbsp; \u0930\u0939\u0947 \u0939\u094b\u0902&#8230;\u092a\u0930 \u092d\u093e\u091c\u092a\u093e \u091c\u0928\u0924\u093e \u092a\u093e\u0930\u094d\u091f\u0940 ,&nbsp; \u0939\u0936\u094d\u0930 \u0915\u0940 \u0924\u0930\u092b \u0924\u0947\u095b\u0940 \u0938\u0947 \u092c\u095d \u0930\u0939\u0940 \u0939\u0948 ! \u0938\u0902\u0918 \u0915\u0940 \u0939\u095c\u092c\u095c\u0940 \u0914\u0930 \u092e\u094b\u0926\u0940 \u091a\u0932\u0928, \u0915\u0948\u0902\u0938\u0930 \u0915\u0940 \u0924\u0930\u0939 \u095e\u0948\u0932 \u0930\u0939\u0947 \u0939\u0948\u0902 ! \u0938\u0924\u094d\u0924\u093e \u0914\u0930 \u0938\u093f\u092f\u093e\u0938\u0924 \u0915\u0940 \u0938\u092e\u091d \u0915\u093e \u0926\u092e-\u0959\u092e , \u0938\u093f\u0930\u094d\u092b \u0938\u0940\u091f\u094b\u0902 \u0915\u0947 \u0905\u0902\u0915\u0917\u0923\u093f\u0924 \u0924\u0915 \u0938\u0940\u092e\u093f\u0924 \u0939\u0948 ! \u0906\u092e \u0906\u0926\u092e\u0940 \u0915\u093e \u0938\u0930\u094b\u0915\u093e\u0930 \u0914\u0930 \u092a\u093e\u0930\u094d\u091f\u0940 \u0935\u093f\u0925 \u0921\u093f\u095e\u0930\u0947\u0902\u0938, \u092d\u093e\u091c\u092a\u093e \u092e\u0947\u0902 \u092c\u0939\u0941\u0924 \u0926\u093f\u0928\u094b\u0902 \u0924\u0915 \u091f\u093f\u0915\u093e \u0930\u0939 \u092a\u093e\u092f\u0947\u0917\u093e \u0915\u0939\u0928\u093e \u092e\u0941\u0936\u094d\u0915\u093f\u0932 \u0939\u0948 ! \u0935\u094d\u092f\u0915\u094d\u0924\u093f-\u0935\u093f\u0936\u0947\u0937 \u0915\u0947 \u091a\u0932\u0924\u0947 , \u0930\u093e\u0937\u094d\u091f\u094d\u0930\u0940\u092f \u0938\u094d\u0924\u0930 \u092a\u0930, \u0915\u094b\u0908 \u092a\u093e\u0930\u094d\u091f\u0940 \u090f\u0915-\u091c\u0941\u091f \u0930\u0939 \u092a\u093e\u092f\u0940 \u0939\u0948 , \u092d\u093e\u0930\u0924\u0940\u092f \u0930\u093e\u091c\u0928\u0940\u0924\u093f \u0915\u0947 \u0907\u0924\u093f\u0939\u093e\u0938 \u092e\u0947\u0902 \u0910\u0938\u093e \u0926\u0947\u0916\u093e \u0928\u0939\u0940\u0902 \u0917\u092f\u093e ! \u092a\u0930\u093f\u0935\u093e\u0930-\u0935\u093e\u0926 \u0915\u0947 \u091a\u0932\u0924\u0947 \u0915\u093e\u0902\u0917\u094d\u0930\u0947\u0938 \u091f\u093f\u0915\u0940 \u0939\u0948 \u0914\u0930 \u0907\u0938 \u092a\u0930\u093f\u0935\u093e\u0930 \u0915\u0947 \u092c\u093f\u0928\u093e \u0915\u093e\u0902\u0917\u094d\u0930\u0947\u0938 \u0915\u093e \u0915\u094b\u0908 \u0935\u091c\u0942\u0926 \u0928\u0939\u0940\u0902&#8230; \u092f\u0947 \u092d\u0940 \u0938\u092c \u091c\u093e\u0928\u0924\u0947 \u0939\u0948\u0902 ! \u092e\u094b\u0926\u0940 \u0939\u0940 \u092d\u093e\u091c\u092a\u093e \u0914\u0930 \u092d\u093e\u091c\u092a\u093e \u0939\u0940 \u092e\u094b\u0926\u0940 \u0939\u0948\u0902&#8230;.\u0910\u0938\u093e \u0938\u0902\u0918 \u0914\u0930 \u0930\u093e\u091c\u0928\u093e\u0925 \u0938\u093f\u0902\u0939 \u0938\u092e\u091d\u093e\u0928\u0947 \u092a\u0930 \u091c\u0941\u091f\u0947 \u0939\u0948\u0902&#8230;.\u092a\u0930 \u092e\u094b\u0926\u0940 \u092c\u093f\u0928\u093e \u092d\u093e\u091c\u092a\u093e \u0928\u0939\u0940\u0902 , \u0910\u0938\u0940 \u0915\u092c\u094d\u0930 \u092d\u0940 \u0916\u094b\u0926\u0924\u0947 \u091c\u093e \u0930\u0939\u0947 \u0939\u0948\u0902 ! \u095b\u093e\u0939\u093f\u0930 \u0939\u0948 &#8230;..\u0907\u0938 \u0915\u092c\u094d\u0930 \u092a\u0930 \u092a\u094d\u0930\u093e\u0930\u094d\u0925\u0928\u093e \u0915\u0930\u0928\u0947 \u092c\u0939\u0941\u0924 \u0915\u092e \u0932\u094b\u0917 \u0906\u092f\u0947\u0902\u0917\u0947\u0902 \u092f\u093e \u0915\u094b\u0908 \u092d\u0940 \u0928\u093e \u0906\u092f\u0947 ! \u0939\u093e\u0932\u093e\u0902\u0915\u093f \u0915\u092c\u094d\u0930 \u0938\u0947 \u092a\u0939\u0932\u0947 \u0907\u0902\u0924\u0915\u093e\u0932 \u095b\u0930\u0942\u0930\u0940 \u0939\u0948 &#8230;\u0914\u0930 \u092d\u093e\u091c\u092a\u093e \u0906\u0924\u094d\u092e-\u0939\u094d\u0924\u094d\u092f\u093e \u0915\u0947 \u095b\u0930\u093f\u092f\u0947 \u0926\u095e\u0928 \u0939\u094b\u0928\u093e \u091a\u093e\u0939\u0924\u0940 \u0939\u0948 ! \u0916\u0941\u0926\u093e \u0916\u0948\u0930 \u0915\u0930\u0947 !<\/p>\n<p style=\"text-align: right;\"> \t<strong>\u0928\u0940\u0930\u091c \u0915\u0947 \u092c\u094d\u0932\u093e\u0917 &#39;\u0932\u0940\u0915 \u0938\u0947 \u0939\u091f\u0915\u0930&#39; \u0938\u0947 \u0938\u093e\u092d\u093e\u0930. \u0938\u0902\u092a\u0930\u094d\u0915: journalistebox@gmail.com<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p> \t1984 \u092e\u0947\u0902, \u0906\u091c \u0915\u0940 \u0924\u093e\u0930\u0940\u0916 \u092e\u0947\u0902 \u0926\u094b \u0930\u093e\u0937\u094d\u091f\u094d\u0930\u0940\u092f \u092a\u093e\u0930\u094d\u091f\u0940 \u092e\u0947\u0902 \u0938\u0947 \u090f\u0915 \u0915\u093e \u0924\u092e\u0917\u093e \u0939\u093e\u0938\u093f\u0932, \u092d\u093e\u091c\u092a\u093e \u0915\u0947 \u092a\u093e\u0938 \u0938\u093f\u0930\u094d\u092b 2 \u0938\u0940\u091f \u0925\u0940 ! \u0907\u092e\u0930\u091c\u0947\u0902\u0938\u0940 \u0915\u0947 \u092c\u093e\u0926 \u0915\u093e\u0902\u0917\u094d\u0930\u0947\u0938 \u0935\u093e\u092a\u093f\u0938 \u0938\u0924\u094d\u0924\u093e \u092e\u0947\u0902 \u0932\u094c\u091f\u0940 \u0925\u0940 \u0914\u0930 \u091c\u0928\u0924\u093e \u092a\u093e\u0930\u094d\u091f\u0940 \u0915\u093e \u0935\u095b\u0928 \u0924\u0947\u095b\u0940 \u0938\u0947 \u0918\u091f \u0930\u0939\u093e \u0925\u093e ! \u091c\u0928\u0924\u093e \u092a\u093e\u0930\u094d\u091f\u0940 \u0915\u0947 \u0926\u094b \u0915\u0926\u094d\u0926\u093e\u0935\u0930 , \u0924\u0924\u094d\u0915\u093e\u0932\u0940\u0928, \u092e\u0902\u0924\u094d\u0930\u0940 (\u0935\u093f\u0926\u0947\u0936 \u092e\u0902\u0924\u094d\u0930\u0940 \u0905\u091f\u0932 \u092c\u093f\u0939\u093e\u0930\u0940 \u0935\u093e\u091c\u092a\u0947\u092f\u0940 \u0914\u0930 \u0938\u0942\u091a\u0928\u093e \u092a\u094d\u0930\u0938\u093e\u0930\u0923 \u092e\u0902\u0924\u094d\u0930\u0940 \u0932\u093e\u0932\u0915\u0943\u0937\u094d\u0923 \u0906\u0921\u0935\u093e\u0928\u0940) \u0905\u0932\u0917 \u0939\u094b\u0915\u0930 \u091c\u0928\u0938\u0902\u0918 \u0915\u094b \u092d\u093e\u091c\u092a\u093e \u0915\u093e \u092e\u0941\u0916\u094c\u091f\u093e \u092a\u0939\u0928\u093e \u091a\u0941\u0915\u0947 \u0925\u0947 ! \u092f\u093e\u0928\u093f 1980 \u092e\u0947\u0902 \u092d\u093e\u091c\u092a\u093e \u0905\u0938\u094d\u0924\u093f\u0924\u094d\u0935 \u092e\u0947\u0902 \u0906\u092f\u0940 !<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-14446","post","type-post","status-publish","format-standard","hentry","category-vividh"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Bhadas4Media.com\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.bhadas4media.com\/old1\/%e0%a4%ad%e0%a4%be%e0%a4%9c%e0%a4%aa%e0%a4%be-%e0%a4%95%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%b7%e0%a5%8d%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%af-%e0%a4%87%e0%a4%82%e0%a4%a4%e0%a4%95%e0%a4%be\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"No. 1 Indian Media News Portal | Bhadas4Media\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u092d\u093e\u091c\u092a\u093e \u0915\u093e \u201d\u0930\u093e\u0937\u094d\u091f\u094d\u0930\u0940\u092f \u0907\u0902\u0924\u0915\u093e\u0932\u201d\u2026. \u0925\u094b\u095c\u093e \u0935\u0958\u094d\u0924 \u0939\u0948 | No. 1 Indian Media News Portal\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.bhadas4media.com\/old1\/%e0%a4%ad%e0%a4%be%e0%a4%9c%e0%a4%aa%e0%a4%be-%e0%a4%95%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%b7%e0%a5%8d%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%af-%e0%a4%87%e0%a4%82%e0%a4%a4%e0%a4%95%e0%a4%be\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2013-09-12T14:18:31+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2013-09-12T14:18:31+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u092d\u093e\u091c\u092a\u093e \u0915\u093e \u201d\u0930\u093e\u0937\u094d\u091f\u094d\u0930\u0940\u092f \u0907\u0902\u0924\u0915\u093e\u0932\u201d\u2026. \u0925\u094b\u095c\u093e \u0935\u0958\u094d\u0924 \u0939\u0948 | No. 1 Indian Media News Portal\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/%e0%a4%ad%e0%a4%be%e0%a4%9c%e0%a4%aa%e0%a4%be-%e0%a4%95%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%b7%e0%a5%8d%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%af-%e0%a4%87%e0%a4%82%e0%a4%a4%e0%a4%95%e0%a4%be\\\/#article\",\"name\":\"\\u092d\\u093e\\u091c\\u092a\\u093e \\u0915\\u093e \\u201d\\u0930\\u093e\\u0937\\u094d\\u091f\\u094d\\u0930\\u0940\\u092f \\u0907\\u0902\\u0924\\u0915\\u093e\\u0932\\u201d\\u2026. \\u0925\\u094b\\u095c\\u093e \\u0935\\u0958\\u094d\\u0924 \\u0939\\u0948 | No. 1 Indian Media News Portal\",\"headline\":\"\\u092d\\u093e\\u091c\\u092a\\u093e \\u0915\\u093e &#8221;\\u0930\\u093e\\u0937\\u094d\\u091f\\u094d\\u0930\\u0940\\u092f \\u0907\\u0902\\u0924\\u0915\\u093e\\u0932&#8221;&#8230;. \\u0925\\u094b\\u095c\\u093e \\u0935\\u0958\\u094d\\u0924 \\u0939\\u0948\",\"author\":{\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/author\\\/adminbhadas\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/#organization\"},\"datePublished\":\"2013-09-12T14:18:31+05:30\",\"dateModified\":\"2013-09-12T14:18:31+05:30\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/%e0%a4%ad%e0%a4%be%e0%a4%9c%e0%a4%aa%e0%a4%be-%e0%a4%95%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%b7%e0%a5%8d%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%af-%e0%a4%87%e0%a4%82%e0%a4%a4%e0%a4%95%e0%a4%be\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/%e0%a4%ad%e0%a4%be%e0%a4%9c%e0%a4%aa%e0%a4%be-%e0%a4%95%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%b7%e0%a5%8d%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%af-%e0%a4%87%e0%a4%82%e0%a4%a4%e0%a4%95%e0%a4%be\\\/#webpage\"},\"articleSection\":\"\\u0935\\u093f\\u0935\\u093f\\u0927\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/%e0%a4%ad%e0%a4%be%e0%a4%9c%e0%a4%aa%e0%a4%be-%e0%a4%95%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%b7%e0%a5%8d%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%af-%e0%a4%87%e0%a4%82%e0%a4%a4%e0%a4%95%e0%a4%be\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/vividh\\\/#listItem\",\"name\":\"\\u0935\\u093f\\u0935\\u093f\\u0927\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/vividh\\\/#listItem\",\"position\":2,\"name\":\"\\u0935\\u093f\\u0935\\u093f\\u0927\",\"item\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/vividh\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/%e0%a4%ad%e0%a4%be%e0%a4%9c%e0%a4%aa%e0%a4%be-%e0%a4%95%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%b7%e0%a5%8d%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%af-%e0%a4%87%e0%a4%82%e0%a4%a4%e0%a4%95%e0%a4%be\\\/#listItem\",\"name\":\"\\u092d\\u093e\\u091c\\u092a\\u093e \\u0915\\u093e &#8221;\\u0930\\u093e\\u0937\\u094d\\u091f\\u094d\\u0930\\u0940\\u092f \\u0907\\u0902\\u0924\\u0915\\u093e\\u0932&#8221;&#8230;. \\u0925\\u094b\\u095c\\u093e \\u0935\\u0958\\u094d\\u0924 \\u0939\\u0948\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/%e0%a4%ad%e0%a4%be%e0%a4%9c%e0%a4%aa%e0%a4%be-%e0%a4%95%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%b7%e0%a5%8d%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%af-%e0%a4%87%e0%a4%82%e0%a4%a4%e0%a4%95%e0%a4%be\\\/#listItem\",\"position\":3,\"name\":\"\\u092d\\u093e\\u091c\\u092a\\u093e \\u0915\\u093e &#8221;\\u0930\\u093e\\u0937\\u094d\\u091f\\u094d\\u0930\\u0940\\u092f \\u0907\\u0902\\u0924\\u0915\\u093e\\u0932&#8221;&#8230;. \\u0925\\u094b\\u095c\\u093e \\u0935\\u0958\\u094d\\u0924 \\u0939\\u0948\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/vividh\\\/#listItem\",\"name\":\"\\u0935\\u093f\\u0935\\u093f\\u0927\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/#organization\",\"name\":\"No. 1 Indian Media News Portal\",\"description\":\"Bhadas4Media\",\"url\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/author\\\/adminbhadas\\\/#author\",\"url\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/author\\\/adminbhadas\\\/\",\"name\":\"Bhadas4Media.com\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/%e0%a4%ad%e0%a4%be%e0%a4%9c%e0%a4%aa%e0%a4%be-%e0%a4%95%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%b7%e0%a5%8d%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%af-%e0%a4%87%e0%a4%82%e0%a4%a4%e0%a4%95%e0%a4%be\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/69ec69a38050e655b541ef6a182052a9e71286fd25d32498a3925ac1b83036ab?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Bhadas4Media.com\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/%e0%a4%ad%e0%a4%be%e0%a4%9c%e0%a4%aa%e0%a4%be-%e0%a4%95%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%b7%e0%a5%8d%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%af-%e0%a4%87%e0%a4%82%e0%a4%a4%e0%a4%95%e0%a4%be\\\/#webpage\",\"url\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/%e0%a4%ad%e0%a4%be%e0%a4%9c%e0%a4%aa%e0%a4%be-%e0%a4%95%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%b7%e0%a5%8d%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%af-%e0%a4%87%e0%a4%82%e0%a4%a4%e0%a4%95%e0%a4%be\\\/\",\"name\":\"\\u092d\\u093e\\u091c\\u092a\\u093e \\u0915\\u093e \\u201d\\u0930\\u093e\\u0937\\u094d\\u091f\\u094d\\u0930\\u0940\\u092f \\u0907\\u0902\\u0924\\u0915\\u093e\\u0932\\u201d\\u2026. \\u0925\\u094b\\u095c\\u093e \\u0935\\u0958\\u094d\\u0924 \\u0939\\u0948 | No. 1 Indian Media News Portal\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/%e0%a4%ad%e0%a4%be%e0%a4%9c%e0%a4%aa%e0%a4%be-%e0%a4%95%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%b7%e0%a5%8d%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%af-%e0%a4%87%e0%a4%82%e0%a4%a4%e0%a4%95%e0%a4%be\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/author\\\/adminbhadas\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/author\\\/adminbhadas\\\/#author\"},\"datePublished\":\"2013-09-12T14:18:31+05:30\",\"dateModified\":\"2013-09-12T14:18:31+05:30\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/#website\",\"url\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/\",\"name\":\"No. 1 Indian Media News Portal\",\"description\":\"Bhadas4Media\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u092d\u093e\u091c\u092a\u093e \u0915\u093e \u201d\u0930\u093e\u0937\u094d\u091f\u094d\u0930\u0940\u092f \u0907\u0902\u0924\u0915\u093e\u0932\u201d\u2026. \u0925\u094b\u095c\u093e \u0935\u0958\u094d\u0924 \u0939\u0948 | No. 1 Indian Media News Portal","description":"","canonical_url":"https:\/\/www.bhadas4media.com\/old1\/%e0%a4%ad%e0%a4%be%e0%a4%9c%e0%a4%aa%e0%a4%be-%e0%a4%95%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%b7%e0%a5%8d%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%af-%e0%a4%87%e0%a4%82%e0%a4%a4%e0%a4%95%e0%a4%be\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bhadas4media.com\/old1\/%e0%a4%ad%e0%a4%be%e0%a4%9c%e0%a4%aa%e0%a4%be-%e0%a4%95%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%b7%e0%a5%8d%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%af-%e0%a4%87%e0%a4%82%e0%a4%a4%e0%a4%95%e0%a4%be\/#article","name":"\u092d\u093e\u091c\u092a\u093e \u0915\u093e \u201d\u0930\u093e\u0937\u094d\u091f\u094d\u0930\u0940\u092f \u0907\u0902\u0924\u0915\u093e\u0932\u201d\u2026. \u0925\u094b\u095c\u093e \u0935\u0958\u094d\u0924 \u0939\u0948 | No. 1 Indian Media News Portal","headline":"\u092d\u093e\u091c\u092a\u093e \u0915\u093e &#8221;\u0930\u093e\u0937\u094d\u091f\u094d\u0930\u0940\u092f \u0907\u0902\u0924\u0915\u093e\u0932&#8221;&#8230;. \u0925\u094b\u095c\u093e \u0935\u0958\u094d\u0924 \u0939\u0948","author":{"@id":"https:\/\/www.bhadas4media.com\/old1\/author\/adminbhadas\/#author"},"publisher":{"@id":"https:\/\/www.bhadas4media.com\/old1\/#organization"},"datePublished":"2013-09-12T14:18:31+05:30","dateModified":"2013-09-12T14:18:31+05:30","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.bhadas4media.com\/old1\/%e0%a4%ad%e0%a4%be%e0%a4%9c%e0%a4%aa%e0%a4%be-%e0%a4%95%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%b7%e0%a5%8d%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%af-%e0%a4%87%e0%a4%82%e0%a4%a4%e0%a4%95%e0%a4%be\/#webpage"},"isPartOf":{"@id":"https:\/\/www.bhadas4media.com\/old1\/%e0%a4%ad%e0%a4%be%e0%a4%9c%e0%a4%aa%e0%a4%be-%e0%a4%95%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%b7%e0%a5%8d%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%af-%e0%a4%87%e0%a4%82%e0%a4%a4%e0%a4%95%e0%a4%be\/#webpage"},"articleSection":"\u0935\u093f\u0935\u093f\u0927"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bhadas4media.com\/old1\/%e0%a4%ad%e0%a4%be%e0%a4%9c%e0%a4%aa%e0%a4%be-%e0%a4%95%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%b7%e0%a5%8d%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%af-%e0%a4%87%e0%a4%82%e0%a4%a4%e0%a4%95%e0%a4%be\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.bhadas4media.com\/old1#listItem","position":1,"name":"Home","item":"https:\/\/www.bhadas4media.com\/old1","nextItem":{"@type":"ListItem","@id":"https:\/\/www.bhadas4media.com\/old1\/vividh\/#listItem","name":"\u0935\u093f\u0935\u093f\u0927"}},{"@type":"ListItem","@id":"https:\/\/www.bhadas4media.com\/old1\/vividh\/#listItem","position":2,"name":"\u0935\u093f\u0935\u093f\u0927","item":"https:\/\/www.bhadas4media.com\/old1\/vividh\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.bhadas4media.com\/old1\/%e0%a4%ad%e0%a4%be%e0%a4%9c%e0%a4%aa%e0%a4%be-%e0%a4%95%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%b7%e0%a5%8d%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%af-%e0%a4%87%e0%a4%82%e0%a4%a4%e0%a4%95%e0%a4%be\/#listItem","name":"\u092d\u093e\u091c\u092a\u093e \u0915\u093e &#8221;\u0930\u093e\u0937\u094d\u091f\u094d\u0930\u0940\u092f \u0907\u0902\u0924\u0915\u093e\u0932&#8221;&#8230;. \u0925\u094b\u095c\u093e \u0935\u0958\u094d\u0924 \u0939\u0948"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.bhadas4media.com\/old1#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.bhadas4media.com\/old1\/%e0%a4%ad%e0%a4%be%e0%a4%9c%e0%a4%aa%e0%a4%be-%e0%a4%95%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%b7%e0%a5%8d%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%af-%e0%a4%87%e0%a4%82%e0%a4%a4%e0%a4%95%e0%a4%be\/#listItem","position":3,"name":"\u092d\u093e\u091c\u092a\u093e \u0915\u093e &#8221;\u0930\u093e\u0937\u094d\u091f\u094d\u0930\u0940\u092f \u0907\u0902\u0924\u0915\u093e\u0932&#8221;&#8230;. \u0925\u094b\u095c\u093e \u0935\u0958\u094d\u0924 \u0939\u0948","previousItem":{"@type":"ListItem","@id":"https:\/\/www.bhadas4media.com\/old1\/vividh\/#listItem","name":"\u0935\u093f\u0935\u093f\u0927"}}]},{"@type":"Organization","@id":"https:\/\/www.bhadas4media.com\/old1\/#organization","name":"No. 1 Indian Media News Portal","description":"Bhadas4Media","url":"https:\/\/www.bhadas4media.com\/old1\/"},{"@type":"Person","@id":"https:\/\/www.bhadas4media.com\/old1\/author\/adminbhadas\/#author","url":"https:\/\/www.bhadas4media.com\/old1\/author\/adminbhadas\/","name":"Bhadas4Media.com","image":{"@type":"ImageObject","@id":"https:\/\/www.bhadas4media.com\/old1\/%e0%a4%ad%e0%a4%be%e0%a4%9c%e0%a4%aa%e0%a4%be-%e0%a4%95%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%b7%e0%a5%8d%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%af-%e0%a4%87%e0%a4%82%e0%a4%a4%e0%a4%95%e0%a4%be\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/69ec69a38050e655b541ef6a182052a9e71286fd25d32498a3925ac1b83036ab?s=96&d=mm&r=g","width":96,"height":96,"caption":"Bhadas4Media.com"}},{"@type":"WebPage","@id":"https:\/\/www.bhadas4media.com\/old1\/%e0%a4%ad%e0%a4%be%e0%a4%9c%e0%a4%aa%e0%a4%be-%e0%a4%95%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%b7%e0%a5%8d%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%af-%e0%a4%87%e0%a4%82%e0%a4%a4%e0%a4%95%e0%a4%be\/#webpage","url":"https:\/\/www.bhadas4media.com\/old1\/%e0%a4%ad%e0%a4%be%e0%a4%9c%e0%a4%aa%e0%a4%be-%e0%a4%95%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%b7%e0%a5%8d%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%af-%e0%a4%87%e0%a4%82%e0%a4%a4%e0%a4%95%e0%a4%be\/","name":"\u092d\u093e\u091c\u092a\u093e \u0915\u093e \u201d\u0930\u093e\u0937\u094d\u091f\u094d\u0930\u0940\u092f \u0907\u0902\u0924\u0915\u093e\u0932\u201d\u2026. \u0925\u094b\u095c\u093e \u0935\u0958\u094d\u0924 \u0939\u0948 | No. 1 Indian Media News Portal","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.bhadas4media.com\/old1\/#website"},"breadcrumb":{"@id":"https:\/\/www.bhadas4media.com\/old1\/%e0%a4%ad%e0%a4%be%e0%a4%9c%e0%a4%aa%e0%a4%be-%e0%a4%95%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%b7%e0%a5%8d%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%af-%e0%a4%87%e0%a4%82%e0%a4%a4%e0%a4%95%e0%a4%be\/#breadcrumblist"},"author":{"@id":"https:\/\/www.bhadas4media.com\/old1\/author\/adminbhadas\/#author"},"creator":{"@id":"https:\/\/www.bhadas4media.com\/old1\/author\/adminbhadas\/#author"},"datePublished":"2013-09-12T14:18:31+05:30","dateModified":"2013-09-12T14:18:31+05:30"},{"@type":"WebSite","@id":"https:\/\/www.bhadas4media.com\/old1\/#website","url":"https:\/\/www.bhadas4media.com\/old1\/","name":"No. 1 Indian Media News Portal","description":"Bhadas4Media","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.bhadas4media.com\/old1\/#organization"}}]},"og:locale":"en_US","og:site_name":"No. 1 Indian Media News Portal | Bhadas4Media","og:type":"article","og:title":"\u092d\u093e\u091c\u092a\u093e \u0915\u093e \u201d\u0930\u093e\u0937\u094d\u091f\u094d\u0930\u0940\u092f \u0907\u0902\u0924\u0915\u093e\u0932\u201d\u2026. \u0925\u094b\u095c\u093e \u0935\u0958\u094d\u0924 \u0939\u0948 | No. 1 Indian Media News Portal","og:url":"https:\/\/www.bhadas4media.com\/old1\/%e0%a4%ad%e0%a4%be%e0%a4%9c%e0%a4%aa%e0%a4%be-%e0%a4%95%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%b7%e0%a5%8d%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%af-%e0%a4%87%e0%a4%82%e0%a4%a4%e0%a4%95%e0%a4%be\/","article:published_time":"2013-09-12T14:18:31+00:00","article:modified_time":"2013-09-12T14:18:31+00:00","twitter:card":"summary","twitter:title":"\u092d\u093e\u091c\u092a\u093e \u0915\u093e \u201d\u0930\u093e\u0937\u094d\u091f\u094d\u0930\u0940\u092f \u0907\u0902\u0924\u0915\u093e\u0932\u201d\u2026. \u0925\u094b\u095c\u093e \u0935\u0958\u094d\u0924 \u0939\u0948 | No. 1 Indian Media News Portal"},"aioseo_meta_data":{"post_id":"14446","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"limit_modified_date":false,"created":"2020-12-21 18:20:39","updated":"2022-10-10 17:15:47","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.bhadas4media.com\/old1\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.bhadas4media.com\/old1\/vividh\/\" title=\"\u0935\u093f\u0935\u093f\u0927\">\u0935\u093f\u0935\u093f\u0927<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u092d\u093e\u091c\u092a\u093e \u0915\u093e \u201d\u0930\u093e\u0937\u094d\u091f\u094d\u0930\u0940\u092f \u0907\u0902\u0924\u0915\u093e\u0932\u201d\u2026. \u0925\u094b\u095c\u093e \u0935\u0958\u094d\u0924 \u0939\u0948\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.bhadas4media.com\/old1"},{"label":"\u0935\u093f\u0935\u093f\u0927","link":"https:\/\/www.bhadas4media.com\/old1\/vividh\/"},{"label":"\u092d\u093e\u091c\u092a\u093e \u0915\u093e &#8221;\u0930\u093e\u0937\u094d\u091f\u094d\u0930\u0940\u092f \u0907\u0902\u0924\u0915\u093e\u0932&#8221;&#8230;. \u0925\u094b\u095c\u093e \u0935\u0958\u094d\u0924 \u0939\u0948","link":"https:\/\/www.bhadas4media.com\/old1\/%e0%a4%ad%e0%a4%be%e0%a4%9c%e0%a4%aa%e0%a4%be-%e0%a4%95%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%b7%e0%a5%8d%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%af-%e0%a4%87%e0%a4%82%e0%a4%a4%e0%a4%95%e0%a4%be\/"}],"_links":{"self":[{"href":"https:\/\/www.bhadas4media.com\/old1\/wp-json\/wp\/v2\/posts\/14446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bhadas4media.com\/old1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bhadas4media.com\/old1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bhadas4media.com\/old1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bhadas4media.com\/old1\/wp-json\/wp\/v2\/comments?post=14446"}],"version-history":[{"count":0,"href":"https:\/\/www.bhadas4media.com\/old1\/wp-json\/wp\/v2\/posts\/14446\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.bhadas4media.com\/old1\/wp-json\/wp\/v2\/media?parent=14446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bhadas4media.com\/old1\/wp-json\/wp\/v2\/categories?post=14446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bhadas4media.com\/old1\/wp-json\/wp\/v2\/tags?post=14446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}