{"id":312,"count":1,"description":"","link":"https:\/\/www.bhadas4media.com\/old1\/tag\/ramgopal-yadav\/","name":"ramgopal yadav","slug":"ramgopal-yadav","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.bhadas4media.com\/old1\/tag\/ramgopal-yadav\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/312\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/tag\\\/ramgopal-yadav\\\/#listItem\",\"name\":\"ramgopal yadav\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/tag\\\/ramgopal-yadav\\\/#listItem\",\"position\":2,\"name\":\"ramgopal yadav\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/312\\\/#collectionpage\",\"url\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/312\\\/\",\"name\":\"ramgopal yadav | No. 1 Indian Media News Portal\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/312\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/#organization\",\"name\":\"No. 1 Indian Media News Portal\",\"description\":\"Bhadas4Media\",\"url\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/#website\",\"url\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/\",\"name\":\"No. 1 Indian Media News Portal\",\"description\":\"Bhadas4Media\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bhadas4media.com\\\/old1\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"ramgopal yadav | No. 1 Indian Media News Portal","description":"","canonical_url":"https:\/\/www.bhadas4media.com\/old1\/tag\/ramgopal-yadav\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.bhadas4media.com\/old1\/wp-json\/wp\/v2\/tags\/312\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.bhadas4media.com\/old1#listItem","position":1,"name":"Home","item":"https:\/\/www.bhadas4media.com\/old1","nextItem":{"@type":"ListItem","@id":"https:\/\/www.bhadas4media.com\/old1\/tag\/ramgopal-yadav\/#listItem","name":"ramgopal yadav"}},{"@type":"ListItem","@id":"https:\/\/www.bhadas4media.com\/old1\/tag\/ramgopal-yadav\/#listItem","position":2,"name":"ramgopal yadav","previousItem":{"@type":"ListItem","@id":"https:\/\/www.bhadas4media.com\/old1#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/www.bhadas4media.com\/old1\/wp-json\/wp\/v2\/tags\/312\/#collectionpage","url":"https:\/\/www.bhadas4media.com\/old1\/wp-json\/wp\/v2\/tags\/312\/","name":"ramgopal yadav | No. 1 Indian Media News Portal","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.bhadas4media.com\/old1\/#website"},"breadcrumb":{"@id":"https:\/\/www.bhadas4media.com\/old1\/wp-json\/wp\/v2\/tags\/312\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/www.bhadas4media.com\/old1\/#organization","name":"No. 1 Indian Media News Portal","description":"Bhadas4Media","url":"https:\/\/www.bhadas4media.com\/old1\/"},{"@type":"WebSite","@id":"https:\/\/www.bhadas4media.com\/old1\/#website","url":"https:\/\/www.bhadas4media.com\/old1\/","name":"No. 1 Indian Media News Portal","description":"Bhadas4Media","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.bhadas4media.com\/old1\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.bhadas4media.com\/old1\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tramgopal yadav\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.bhadas4media.com\/old1"},{"label":"ramgopal yadav","link":"https:\/\/www.bhadas4media.com\/old1\/tag\/ramgopal-yadav\/"}],"_links":{"self":[{"href":"https:\/\/www.bhadas4media.com\/old1\/wp-json\/wp\/v2\/tags\/312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bhadas4media.com\/old1\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.bhadas4media.com\/old1\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.bhadas4media.com\/old1\/wp-json\/wp\/v2\/posts?tags=312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}